{"id":1511,"date":"2017-04-20T14:18:24","date_gmt":"2017-04-20T17:18:24","guid":{"rendered":"http:\/\/eba.ufmg.br\/nossa-escola\/?p=1511"},"modified":"2017-04-26T21:53:44","modified_gmt":"2017-04-27T00:53:44","slug":"obra-coletiva","status":"publish","type":"post","link":"https:\/\/www.eba.ufmg.br\/index.php\/obra-coletiva\/2017\/04\/","title":{"rendered":"Obra coletiva"},"content":{"rendered":"<h1 style=\"text-align: justify;\"><strong><span style=\"color: #0000ff;\">Obra coletiva<\/span><\/strong><\/h1>\n<h2 class=\"preto\" style=\"text-align: justify;\"><strong><span style=\"color: #ff0000;\">EBA chega aos 60 anos valorizando a diversidade e uma cultura assentada no compartilhamento<\/span><\/strong><\/h2>\n<p class=\"autor\" style=\"text-align: right;\">Itamar Rigueira Jr.<\/p>\n<p class=\"primeiroparagrafo\" style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1518\" src=\"http:\/\/eba.ufmg.br\/\/wp-content\/uploads\/2017\/04\/EBA-19-300x207.jpg\" alt=\"\" width=\"300\" height=\"207\" srcset=\"https:\/\/www.eba.ufmg.br\/wp-content\/uploads\/2017\/04\/EBA-19-300x207.jpg 300w, https:\/\/www.eba.ufmg.br\/wp-content\/uploads\/2017\/04\/EBA-19.jpg 386w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p class=\"primeiroparagrafo\" style=\"text-align: center;\">Detalhe do pr\u00e9dio da EBA: tempos marcados por mobiliza\u00e7\u00e3o pol\u00edtica e integra\u00e7\u00e3o da comunidade. Foto: Carol Prado\/UFMG.<\/p>\n<p class=\"primeiroparagrafo\" style=\"text-align: justify;\">Em 1957, quando foi criado o curso de Artes, na Escola de Arquitetura, iniciava-se a hist\u00f3ria da Escola de Belas Artes da UFMG. Uma trajet\u00f3ria feita de mudan\u00e7as f\u00edsicas, resist\u00eancia, ousadia, crescimento e pioneirismo. Sessenta anos depois, a EBA continua disposta a mudar, \u00e0 procura de, cada vez mais, enxergar-se e atuar como uma comunidade.<\/p>\n<p style=\"text-align: justify;\">\u00c0s v\u00e9speras do in\u00edcio de uma nova gest\u00e3o na Escola, o esp\u00edrito dominante \u00e9 o de valorizar a diversidade e a pluralidade, que sempre marcaram a EBA, para consolidar a unidade. &#8220;Buscamos formas de ressignificar nossa identidade, que se fez plural ao longo dos anos, afirmando a diversidade e o compartilhamento de viv\u00eancias e experi\u00eancias art\u00edsticas, cient\u00edficas e culturais&#8221;, afirma o professor Cristiano Bickel, diretor rec\u00e9m-eleito, que toma posse nesta semana. &#8220;Os novos tempos da Escola de Belas Artes s\u00e3o sinalizados pelas mobiliza\u00e7\u00f5es pol\u00edticas e forte integra\u00e7\u00e3o da comunidade, atuando em defesa das artes, da cultura e da educa\u00e7\u00e3o p\u00fablica de qualidade e de efetividade social.&#8221;<\/p>\n<p style=\"text-align: justify;\">Depois de uma festa que reuniu membros da comunidade de todas as \u00e9pocas, a Escola vai comemorar o anivers\u00e1rio com a cria\u00e7\u00e3o coletiva de sua nova identidade visual, com base em pesquisa com a comunidade. Tamb\u00e9m ao longo deste ano, arquivos pessoais e institucionais v\u00e3o compor exposi\u00e7\u00e3o de fotos que ser\u00e1 distribu\u00edda nos diversos espa\u00e7os da Unidade. A ideia, segundo Cristiano Bickel, \u00e9 que &#8220;as pessoas, ao percorrerem a Escola, conhe\u00e7am os seus diversos tempos e percursos, em imagens e hist\u00f3rias contadas de diferentes pontos de vista, do pessoal ao institucional&#8221;. A celebra\u00e7\u00e3o vai se completar com o lan\u00e7amento de document\u00e1rio e livro sobre a hist\u00f3ria e as mem\u00f3rias da EBA, que aproveitam material de pesquisa e entrevistas iniciadas h\u00e1 15 anos.<\/p>\n<h2 style=\"text-align: justify;\"><strong><span style=\"color: #0000ff;\">Entre salas e galp\u00f5es<\/span><\/strong><\/h2>\n<p style=\"text-align: justify;\">Amea\u00e7ado de extin\u00e7\u00e3o por conta de desaven\u00e7as com alunos da Escola de Arquitetura, o curso de Artes chegou a ter sede em pr\u00e9dio da Rua S\u00e3o Paulo, no Centro de Belo Horizonte, antes de chegar \u00e0 Pampulha. Nos primeiros tempos no campus, dividiu-se entre aulas te\u00f3ricas no pr\u00e9dio da Reitoria e atividades pr\u00e1ticas em galp\u00f5es remanescentes da constru\u00e7\u00e3o. Em 1972, a Escola de Belas Artes mudou-se para o edif\u00edcio em que est\u00e1 instalada at\u00e9 hoje, um dos primeiros dedicados a uma unidade acad\u00eamica no campus Pampulha.<\/p>\n<p style=\"text-align: justify;\">Os poucos alunos e professores se distribu\u00edam entre os departamentos de Desenho e Artes Pl\u00e1sticas, e come\u00e7ava a se desenvolver, na d\u00e9cada de 1970, a \u00e1rea de fotografia e cinema. A essa altura, a Escola ganhara visibilidade por causa do Festival de Inverno, criado em 1967, &#8220;que se afirmava como espa\u00e7o de criatividade, liberdade e at\u00e9 de oposi\u00e7\u00e3o ao regime militar&#8221;, como lembra o professor Evandro Lemos, decano da EBA e um dos respons\u00e1veis, juntamente com a professora Lucia Gouv\u00eaa Pimentel, pela produ\u00e7\u00e3o do livro de mem\u00f3rias da Escola. Esse projeto tem a participa\u00e7\u00e3o de Mariana Tavares, bolsista de p\u00f3s-doutorado da Capes.<\/p>\n<p style=\"text-align: justify;\">Sob est\u00edmulo de uma demanda da Reitoria pela recupera\u00e7\u00e3o de grandes telas da Escola de M\u00fasica, a EBA iniciou, no fim da d\u00e9cada de 1970, a trajet\u00f3ria que culminaria, primeiro, na cria\u00e7\u00e3o do Centro de Conserva\u00e7\u00e3o e Restaura\u00e7\u00e3o de Bens Culturais M\u00f3veis (Cecor), que se tornaria refer\u00eancia internacional, e, mais tarde, na gradua\u00e7\u00e3o espec\u00edfica.<\/p>\n<p style=\"text-align: justify;\">Os anos 1980 ficaram marcados por mais pioneirismo com a cria\u00e7\u00e3o dos cursos de anima\u00e7\u00e3o em Cinema e de Estilismo e Modelagem de Vestu\u00e1rio, embri\u00f5es das futuras gradua\u00e7\u00f5es em Cinema de Anima\u00e7\u00e3o e Artes Digitais e em Design de Moda.<\/p>\n<p style=\"text-align: justify;\">Nos anos 1990, surgiram tamb\u00e9m o mestrado e o doutorado em Artes e a gradua\u00e7\u00e3o em Artes C\u00eanicas, hoje denominada gradua\u00e7\u00e3o em Teatro. Mais recentemente, a EBA passou a ofertar cursos com outras unidades \u2013 Design (Escola de Arquitetura) e Museologia (Escola de Ci\u00eancia da Informa\u00e7\u00e3o).<\/p>\n<p style=\"text-align: justify;\">&#8220;As novas gradua\u00e7\u00f5es de Cinema de Anima\u00e7\u00e3o e Artes Digitais, Conserva\u00e7\u00e3o e Restaura\u00e7\u00e3o de Bens Culturais M\u00f3veis, Dan\u00e7a e Design de Moda atenderam a demandas represadas e foram viabilizadas pelo Reuni [<em>plano de reestrutura\u00e7\u00e3o das universidades federais<\/em>]. Esses cursos t\u00eam sido estruturados em ampla discuss\u00e3o com a sociedade&#8221;, ressalta Evandro Lemos. &#8220;A Escola cresceu muito nos \u00faltimos anos, o corpo docente mais que dobrou. Hoje somos uma escola m\u00e9dia num espa\u00e7o pequeno. Mas com forte inser\u00e7\u00e3o acad\u00eamica, art\u00edstica e cultural.&#8221;<\/p>\n<div class=\"bordaazul\" style=\"text-align: justify;\">\n<h2><span style=\"color: #0000ff;\"><strong>Fora dos padr\u00f5es<\/strong><\/span><\/h2>\n<p>&#8220;A Escola de Belas Artes foi sempre uma unidade sui generis, fora dos padr\u00f5es&#8221;, define a professora aposentada Pomp\u00e9ia Peret, que chegou como aluna em uma \u00e9poca em que as aulas eram ministradas em instala\u00e7\u00f5es prec\u00e1rias na Pampulha. &#8220;Havia um grupo de professores que eram artistas importantes, como o \u00c1lvaro Apocalypse, e os alunos tinham n\u00edvel cultural muito alto. O ambiente era de forte integra\u00e7\u00e3o&#8221;. relembra.<\/p>\n<p>Em 35 entrevistas sobre as mem\u00f3rias associadas \u00e0 Escola que realizou h\u00e1 mais de 15 anos, Pomp\u00e9ia Peret conheceu ou confirmou hist\u00f3rias como a das atividades realizadas no terreno onde come\u00e7ava a ser constru\u00eddo o Pal\u00e1cio das Artes e a do temporal que inundou a pequena biblioteca da EBA e danificou, j\u00e1 na Pampulha, trabalhos de alunos.<\/p>\n<p>A professora em\u00e9rita Beatriz Coelho lembra que a expans\u00e3o da EBA para novas \u00e1reas sofreu resist\u00eancia, nos primeiros tempos, por parte dos defensores da exclusividade das artes pl\u00e1sticas. Da mesma forma, o in\u00edcio dos trabalhos de restaura\u00e7\u00e3o das telas da Escola de M\u00fasica, sob coordena\u00e7\u00e3o do Iphan, foi acompanhado de in\u00edcio apenas pelos professores \u2013 s\u00f3 mais tarde houve ades\u00e3o dos estudantes. Mesmo depois de aposentada, Beatriz manteve atividades volunt\u00e1rias na Escola por mais oito anos. &#8220;Aprendi muito na conviv\u00eancia com os colegas e com os alunos&#8221;, diz a professora, que dirigiu a EBA de 1976 a 1981.<\/p>\n<h2><strong><span style=\"color: #0000ff;\">Bem acolhido<\/span><\/strong><\/h2>\n<p>Representante de uma gera\u00e7\u00e3o mais nova de professores, Carlos Henrique Falci, do curso de Cinema de Anima\u00e7\u00e3o e Artes Digitais, salienta que a Escola de Belas Artes \u00e9 caracterizada hoje por uma grande variedade de vis\u00f5es por parte de professores e alunos. &#8220;Tenho forma\u00e7\u00e3o transdisciplinar, misturada, e fui muito bem acolhido. Mas ainda podemos aproveitar mais as possibilidades criadas por essa diversidade, tamb\u00e9m na rela\u00e7\u00e3o com a Universidade. Estamos nos aproximando das outras unidades, e est\u00e1 cada vez mais claro o potencial de intera\u00e7\u00e3o das artes com as outras \u00e1reas&#8221;, afirma.<\/p>\n<p>Entre as lembran\u00e7as mais fortes do artista visual e &#8220;fazedor de coisas&#8221; Paulo Nazareth, ex-aluno que deixou as salas de aula em 2006, est\u00e3o o tr\u00e2nsito livre pelo ateli\u00ea de escultura, a possibilidade de trabalhar com gravura em hor\u00e1rios diversos e o contato fluente entre alunos mais jovens e veteranos. &#8220;Contei sempre com apoio de todos na Belas Artes, incluindo as faxineiras que guardavam material de reciclagem para minha produ\u00e7\u00e3o. Mesmo depois de terminado o curso, mantive contato e trabalhei por l\u00e1, com ajuda de professores, funcion\u00e1rios e do Diret\u00f3rio Acad\u00eamico&#8221;, conta Nazareth.<\/p>\n<\/div>\n<h2 style=\"text-align: justify;\"><strong><span style=\"color: #0000ff;\">EBA em n\u00fameros<\/span><\/strong><\/h2>\n<p style=\"text-align: justify;\"><strong>1.341<\/strong> estudantes<\/p>\n<p style=\"text-align: justify;\"><strong>111<\/strong> professores<\/p>\n<p style=\"text-align: justify;\"><strong>63<\/strong> servidores t\u00e9cnicos e administrativos em educa\u00e7\u00e3o<\/p>\n<p style=\"text-align: justify;\"><strong>139<\/strong> projetos de pesquisa<\/p>\n<p style=\"text-align: justify;\"><strong>27<\/strong> grupos de pesquisa<\/p>\n<p style=\"text-align: justify;\"><strong>410<\/strong> a\u00e7\u00f5es de extens\u00e3o<\/p>\n<p style=\"text-align: justify;\"><strong>39<\/strong> projetos de ensino<\/p>\n<p style=\"text-align: justify;\"><strong>40<\/strong> defesas por ano na p\u00f3s-gradua\u00e7\u00e3o (m\u00e9dia)<\/p>\n<p style=\"text-align: justify;\"><strong>14<\/strong> conv\u00eanios internacionais<\/p>\n<table style=\"height: 233px;\" width=\"793\">\n<tbody>\n<tr>\n<td width=\"288\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1512 aligncenter\" src=\"http:\/\/eba.ufmg.br\/\/wp-content\/uploads\/2017\/04\/EBA-11-Yara-Tupinamb\u00e1-1970-300x215.jpg\" alt=\"\" width=\"300\" height=\"215\" srcset=\"https:\/\/www.eba.ufmg.br\/wp-content\/uploads\/2017\/04\/EBA-11-Yara-Tupinamb\u00e1-1970-300x215.jpg 300w, https:\/\/www.eba.ufmg.br\/wp-content\/uploads\/2017\/04\/EBA-11-Yara-Tupinamb\u00e1-1970-768x549.jpg 768w, https:\/\/www.eba.ufmg.br\/wp-content\/uploads\/2017\/04\/EBA-11-Yara-Tupinamb\u00e1-1970.jpg 902w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p style=\"text-align: center;\">Yara Tupynamb\u00e1 (de costas) ministra aula no &#8220;piscin\u00e3o&#8221;, no in\u00edcio dos anos 1970<\/p>\n<\/td>\n<td width=\"288\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1513 aligncenter\" src=\"http:\/\/eba.ufmg.br\/\/wp-content\/uploads\/2017\/04\/Arte-45-Atividade-estudantes-abril-2017-300x199.jpg\" alt=\"\" width=\"300\" height=\"199\" srcset=\"https:\/\/www.eba.ufmg.br\/wp-content\/uploads\/2017\/04\/Arte-45-Atividade-estudantes-abril-2017-300x199.jpg 300w, https:\/\/www.eba.ufmg.br\/wp-content\/uploads\/2017\/04\/Arte-45-Atividade-estudantes-abril-2017-768x510.jpg 768w, https:\/\/www.eba.ufmg.br\/wp-content\/uploads\/2017\/04\/Arte-45-Atividade-estudantes-abril-2017-75x50.jpg 75w, https:\/\/www.eba.ufmg.br\/wp-content\/uploads\/2017\/04\/Arte-45-Atividade-estudantes-abril-2017.jpg 901w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p style=\"text-align: center;\">Atividade com estudantes em abril de 2017<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Fonte: <a href=\"https:\/\/www.ufmg.br\/boletim\/bol1973\/4e5.shtml\">Boletim UFMG, n\u00ba 1.973 &#8211; ano 43 &#8211; 17 de abril de 2017<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Obra coletiva EBA chega aos 60 anos valorizando a diversidade e uma cultura assentada no compartilhamento Itamar Rigueira Jr. Detalhe do pr\u00e9dio da EBA: tempos marcados por mobiliza\u00e7\u00e3o pol\u00edtica e integra\u00e7\u00e3o da comunidade. Foto: Carol Prado\/UFMG. Em 1957, quando foi<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","footnotes":""},"categories":[13],"tags":[19],"class_list":["post-1511","post","type-post","status-publish","format-standard","hentry","category-imprensa","tag-boletim-ufmg"],"_links":{"self":[{"href":"https:\/\/www.eba.ufmg.br\/index.php\/wp-json\/wp\/v2\/posts\/1511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eba.ufmg.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eba.ufmg.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eba.ufmg.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eba.ufmg.br\/index.php\/wp-json\/wp\/v2\/comments?post=1511"}],"version-history":[{"count":7,"href":"https:\/\/www.eba.ufmg.br\/index.php\/wp-json\/wp\/v2\/posts\/1511\/revisions"}],"predecessor-version":[{"id":1556,"href":"https:\/\/www.eba.ufmg.br\/index.php\/wp-json\/wp\/v2\/posts\/1511\/revisions\/1556"}],"wp:attachment":[{"href":"https:\/\/www.eba.ufmg.br\/index.php\/wp-json\/wp\/v2\/media?parent=1511"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eba.ufmg.br\/index.php\/wp-json\/wp\/v2\/categories?post=1511"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eba.ufmg.br\/index.php\/wp-json\/wp\/v2\/tags?post=1511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}